{"id":1870,"date":"2026-04-21T08:18:06","date_gmt":"2026-04-21T08:18:06","guid":{"rendered":"https:\/\/www.upeople.nl\/for-candidates\/professional-guidance\/"},"modified":"2026-08-21T11:07:11","modified_gmt":"2026-08-21T11:07:11","slug":"professionele-begeleiding","status":"publish","type":"page","link":"https:\/\/www.upeople.nl\/nl\/voor-kandidaten\/professionele-begeleiding\/","title":{"rendered":"Professionele begeleiding"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; sd_row_height=&#8221;row_500px&#8221; sd_row_bottom_shape=&#8221;row_bottom_shape_3&#8243; sd_shape_color=&#8221;shape_color_white&#8221; sd_black_gradient=&#8221;yes&#8221; css=&#8221;.vc_custom_1781253986590{background-image: url(https:\/\/www.upeople.nl\/wp-content\/uploads\/2026\/06\/personal-guidance-v2.jpg?id=933) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column]\r\n        <div class=\"sd-block-title \">\r\n            <h1 class=\"sd-block-title-htag  marginbottom-0px align-center color-white font-large\r\n            \">Professionele begeleiding<\/h1>\r\n        <\/div>[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; sd_bg_color=&#8221;bg_white&#8221;][vc_column][vc_row_inner][vc_column_inner width=&#8221;1\/12&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;10\/12&#8243;]\r\n        <div class=\"sd-block-text  marginbottom-0px color-black background_color-gray\r\n        \">\r\n            <p style=\"text-align: center;\">Wij bieden onze kandidaten professionele en persoonlijke begeleiding. We beginnen met het vinden van de juiste functie en zorgen voor een optimale match tussen de vaardigheden en wensen van de kandidaat en de functie. We werken samen met topwerkgevers die een prettige werkomgeving bieden en internationaal geori\u00ebnteerd zijn.<\/p>\n<p style=\"text-align: center;\">We begeleiden je door het hele sollicitatieproces, bereiden je voor op elk sollicitatiegesprek en geven je alle informatie over de functie en de organisatie. We staan voor je klaar met vragen en advies via telefoon, Teams of e-mail en je kunt altijd een snelle reactie van ons verwachten.<\/p>\n\r\n        <\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/12&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; sd_bg_color=&#8221;bg_gray&#8221; sd_reverse_columns=&#8221;yes&#8221;][vc_column css_animation=&#8221;fadeInLeft&#8221; width=&#8221;5\/12&#8243;]\r\n        <div class=\"sd-block-title \">\r\n            <h2 class=\"sd-block-title-htag  marginbottom-30px align-left\r\n            \">Het sollicitatieproces<\/h2>\r\n        <\/div>\r\n        <div class=\"sd-block-faq-single  marginbottom-30px color-black open-yes\">\r\n\t\t\t<div class=\"faq-inner-single\">\r\n\t\t\t\t<div class=\"faq-question\">\r\n\t\t\t\t\t<div class=\"faq-icon\">1<\/div>\r\n\t\t\t\t\t\r\n        <div class=\"sd-block-title \">\r\n            <h3 class=\"sd-block-title-htag  marginbottom-0px align-left color-black font-mini\r\n            \">Neem contact op!<\/h3>\r\n        <\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"faq-answer\">\r\n\t\t\t\t\t\r\n        <div class=\"sd-block-text  marginbottom-0px color-black\r\n        \">\r\n            <p>Zie jij jezelf in deze rol? Stuur ons je cv en begin aan je avontuur. We nemen binnen enkele dagen contact met je op. We laten je weten of we een eerste gesprek willen inplannen.<\/p>\n\r\n        <\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n        <\/div>\r\n        <div class=\"sd-block-faq-single  marginbottom-30px color-black open-no\">\r\n\t\t\t<div class=\"faq-inner-single\">\r\n\t\t\t\t<div class=\"faq-question\">\r\n\t\t\t\t\t<div class=\"faq-icon\">2<\/div>\r\n\t\t\t\t\t\r\n        <div class=\"sd-block-title \">\r\n            <h3 class=\"sd-block-title-htag  marginbottom-0px align-left color-black font-mini\r\n            \">Elkaar leren kennen<\/h3>\r\n        <\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"faq-answer\">\r\n\t\t\t\t\t\r\n        <div class=\"sd-block-text  marginbottom-0px color-black\r\n        \">\r\n            <p>Samen met de verantwoordelijke recruitmentconsultant bespreek je of jouw profiel goed aansluit bij de functie. Je bekijkt ook of de organisatie en jouw ambities goed op elkaar aansluiten. Deze kennismaking vindt plaats op ons kantoor of via Teams.<\/p>\n\r\n        <\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n        <\/div>\r\n        <div class=\"sd-block-faq-single  marginbottom-30px color-black open-no\">\r\n\t\t\t<div class=\"faq-inner-single\">\r\n\t\t\t\t<div class=\"faq-question\">\r\n\t\t\t\t\t<div class=\"faq-icon\">3<\/div>\r\n\t\t\t\t\t\r\n        <div class=\"sd-block-title \">\r\n            <h3 class=\"sd-block-title-htag  marginbottom-0px align-left color-black font-mini\r\n            \">De introductie<\/h3>\r\n        <\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"faq-answer\">\r\n\t\t\t\t\t\r\n        <div class=\"sd-block-text  marginbottom-0px color-black\r\n        \">\r\n            <p>Als er een goede match is, stellen we je graag voor aan onze klant. Het doel is dat je binnen twee weken je eerste sollicitatiegesprek bij onze klant hebt.<\/p>\n\r\n        <\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n        <\/div>\r\n        <div class=\"sd-block-faq-single  marginbottom-30px color-black open-no\">\r\n\t\t\t<div class=\"faq-inner-single\">\r\n\t\t\t\t<div class=\"faq-question\">\r\n\t\t\t\t\t<div class=\"faq-icon\">4<\/div>\r\n\t\t\t\t\t\r\n        <div class=\"sd-block-title \">\r\n            <h3 class=\"sd-block-title-htag  marginbottom-0px align-left color-black font-mini\r\n            \">Het interview<\/h3>\r\n        <\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"faq-answer\">\r\n\t\t\t\t\t\r\n        <div class=\"sd-block-text  marginbottom-0px color-black\r\n        \">\r\n            <p>Geweldig, onze klant wil graag met je spreken! Voordat je gesprek plaatsvindt, ontvang je van ons alle informatie die je nodig hebt voor een succesvol en prettig gesprek. Een positief gesprek wordt meestal gevolgd door een tweede gesprek en soms zelfs door een derde. Er is volop gelegenheid om je vragen te stellen!<\/p>\n\r\n        <\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n        <\/div>\r\n        <div class=\"sd-block-faq-single  marginbottom-0px color-black open-no mobile_marginbottom-0px\">\r\n\t\t\t<div class=\"faq-inner-single\">\r\n\t\t\t\t<div class=\"faq-question\">\r\n\t\t\t\t\t<div class=\"faq-icon\">5<\/div>\r\n\t\t\t\t\t\r\n        <div class=\"sd-block-title \">\r\n            <h3 class=\"sd-block-title-htag  marginbottom-0px align-left color-black font-mini\r\n            \">Aan de slag!<\/h3>\r\n        <\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"faq-answer\">\r\n\t\t\t\t\t\r\n        <div class=\"sd-block-text  marginbottom-0px color-black\r\n        \">\r\n            <p>Zijn zowel jij als onze klant nog steeds enthousiast? Dan volgt er een aantrekkelijk aanbod. Na acceptatie van het aanbod plannen we je eerste werkdag in en kan het avontuur beginnen.<\/p>\n\r\n        <\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n        <\/div>[\/vc_column][vc_column width=&#8221;1\/12&#8243;][\/vc_column][vc_column width=&#8221;6\/12&#8243;]\r\n        <div class=\"sd-block-image  align-Left marginbottom-0px mobile_marginbottom-30px\r\n        \"><img decoding=\"async\" title=\"\" alt=\"\" src=\"https:\/\/www.upeople.nl\/wp-content\/uploads\/2026\/07\/800X600-tug.jpg\">\r\n        <\/div>[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; sd_row_bottom_shape=&#8221;row_bottom_shape_2&#8243; sd_shape_color=&#8221;shape_color_black&#8221; el_class=&#8221;team-overview-row&#8221; el_id=&#8221;form&#8221;][vc_column width=&#8221;2\/12&#8243;][\/vc_column][vc_column width=&#8221;1\/3&#8243; offset=&#8221;vc_col-lg-3 vc_col-md-4 vc_col-xs-6&#8243;]\r\n        <div class=\"sd-block-title \">\r\n            <h3 class=\"sd-block-title-htag  marginbottom-30px align-left color-black\r\n            \">Meer informatie?<\/h3>\r\n        <\/div>\r\n                    <div class=\"sd-block-team bg-color-black marginbottom-0px mobile_marginbottom-30px\r\n                    \">\r\n\t\t\t\t\t\t\t\t<figure class=\"sd-block-team-profile-picture\">\r\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.upeople.nl\/wp-content\/uploads\/2026\/06\/Elena_DK_001_520x380_Website_Team.png\">\r\n\t\t\t\t\t\t\t\t<\/figure>\r\n                        <div class=\"sd-block-team-content\">\r\n                            \r\n        <div class=\"sd-block-title \">\r\n            <h3 class=\"sd-block-title-htag  marginbottom-0px align-left color-white font-mini\r\n            \">Elena Olteanu<\/h3>\r\n        <\/div>\r\n                             \r\n        <div class=\"sd-block-text  marginbottom-0px color-white team-function\r\n        \">\r\n            <p>Senior Recruitment Consultant<\/p>\n\r\n        <\/div>\r\n                            <span class=\"team-info mail\"><a href=\"mailto:elena@upeople.nl\"><svg viewBox=\"0 0 20 16\" width=\"15px\" height=\"15px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M2,16c-.55,0-1.02-.2-1.41-.59s-.59-.86-.59-1.41V2C0,1.45.2.98.59.59s.86-.59,1.41-.59h16c.55,0,1.02.2,1.41.59s.59.86.59,1.41v12c0,.55-.2,1.02-.59,1.41s-.86.59-1.41.59H2ZM10,9l8-5v-2l-8,5L2,2v2l8,5Z\" fill=\"currentColor\" \/><\/svg><p>elena@upeople.nl<\/p><\/a><\/span>\r\n                            <span class=\"team-info phone\"><a href=\"tel:0031630111222\"><svg id=\"Layer_1\" height=\"15\" width=\"15\" data-name=\"Layer 1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 18.05\"><path fill=\"currentColor\" d=\"M16,9c0-1.95-.68-3.6-2.04-4.96s-3.01-2.04-4.96-2.04V0c1.25,0,2.42.24,3.51.71s2.04,1.12,2.85,1.93,1.45,1.76,1.93,2.85.71,2.26.71,3.51h-2ZM12,9c0-.83-.29-1.54-.88-2.13s-1.29-.88-2.13-.88v-2c1.38,0,2.56.49,3.54,1.46s1.46,2.15,1.46,3.54h-2ZM16.95,18.05c-2.08,0-4.14-.45-6.18-1.36-2.03-.91-3.88-2.2-5.55-3.86s-2.95-3.52-3.86-5.55C.45,5.24,0,3.18,0,1.1c0-.3.1-.55.3-.75S.75.05,1.05.05h4.05c.23,0,.44.08.63.24s.29.35.33.56l.65,3.5c.03.27.03.49-.03.68s-.14.34-.28.48l-2.43,2.45c.33.62.73,1.21,1.19,1.79s.96,1.13,1.51,1.66c.52.52,1.06,1,1.63,1.44s1.17.85,1.8,1.21l2.35-2.35c.15-.15.35-.26.59-.34s.48-.1.71-.06l3.45.7c.23.07.43.19.58.36s.23.37.23.59v4.05c0,.3-.1.55-.3.75s-.45.3-.75.3Z\"\/><\/svg><p>+31 6 30 11 12 22<\/p><\/a><\/span>\r\n                            <span class=\"team-info whatsapp\"><a href=\"https:\/\/web.whatsapp.com\/send?text=31630111222\" target=\"_blank\"><svg width=\"15\" height=\"15\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path fill=\"currentColor\" d=\"M380.9 97.1C339 55.1 283.2 32 223.9 32c-122.4 0-222 99.6-222 222 0 39.1 10.2 77.3 29.6 111L0 480l117.7-30.9c32.4 17.7 68.9 27 106.1 27h.1c122.3 0 224.1-99.6 224.1-222 0-59.3-25.2-115-67.1-157zm-157 341.6c-33.2 0-65.7-8.9-94-25.7l-6.7-4-69.8 18.3L72 359.2l-4.4-7c-18.5-29.4-28.2-63.3-28.2-98.2 0-101.7 82.8-184.5 184.6-184.5 49.3 0 95.6 19.2 130.4 54.1 34.8 34.9 56.2 81.2 56.1 130.5 0 101.8-84.9 184.6-186.6 184.6zm101.2-138.2c-5.5-2.8-32.8-16.2-37.9-18-5.1-1.9-8.8-2.8-12.5 2.8-3.7 5.6-14.3 18-17.6 21.8-3.2 3.7-6.5 4.2-12 1.4-32.6-16.3-54-29.1-75.5-66-5.7-9.8 5.7-9.1 16.3-30.3 1.8-3.7.9-6.9-.5-9.7-1.4-2.8-12.5-30.1-17.1-41.2-4.5-10.8-9.1-9.3-12.5-9.5-3.2-.2-6.9-.2-10.6-.2-3.7 0-9.7 1.4-14.8 6.9-5.1 5.6-19.4 19-19.4 46.3 0 27.3 19.9 53.7 22.6 57.4 2.8 3.7 39.1 59.7 94.8 83.8 35.2 15.2 49 16.5 66.6 13.9 10.7-1.6 32.8-13.4 37.4-26.4 4.6-13 4.6-24.1 3.2-26.4-1.3-2.5-5-3.9-10.5-6.6z\"><\/path><\/svg><p>WhatsApp Elena<\/p><\/a><\/span>\r\n                            <span class=\"team-info linkedin\"><a href=\"https:\/\/www.linkedin.com\/in\/elena-manica-olteanu\/\" target=\"_blank\"><svg width=\"15\" height=\"15\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 448 512\"><path fill=\"currentColor\" d=\"M100.28 448H7.4V148.9h92.88zM53.79 108.1C24.09 108.1 0 83.5 0 53.8a53.79 53.79 0 0 1 107.58 0c0 29.7-24.1 54.3-53.79 54.3zM447.9 448h-92.68V302.4c0-34.7-.7-79.2-48.29-79.2-48.29 0-55.69 37.7-55.69 76.7V448h-92.78V148.9h89.08v40.8h1.3c12.4-23.5 42.69-48.3 87.88-48.3 94 0 111.28 61.9 111.28 142.3V448z\"><\/path><\/svg><p>Volg mij op LinkedIn<\/p><\/a><\/span>\r\n                        <\/div>\r\n                    <\/div>\r\n                [\/vc_column][vc_column width=&#8221;1\/12&#8243; offset=&#8221;vc_hidden-xs&#8221;][\/vc_column][vc_column css_animation=&#8221;fadeInRight&#8221; width=&#8221;5\/12&#8243; offset=&#8221;vc_col-xs-6&#8243;]\r\n        <div class=\"sd-block-title \">\r\n            <h3 class=\"sd-block-title-htag  marginbottom-30px align-left color-black\r\n            \">Open sollicitatie<\/h3>\r\n        <\/div>\r\n        <div class=\"sd-apply-block\">\r\n            <sd-sdcx-vacancies-apply :publication-i-d=\"1\" :is-open-application=\"true\"><\/sd-sdcx-vacancies-apply>\r\n        <\/div>[\/vc_column][vc_column width=&#8221;1\/12&#8243;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; sd_bg_color=&#8221;bg_black&#8221;][vc_column]\r\n        <div class=\"sd-block-title \">\r\n            <h2 class=\"sd-block-title-htag  marginbottom-30px align-center color-white font-large\r\n            \">Wat onze kandidaten over ons zeggen<\/h2>\r\n        <\/div>\n        <div class=\"unique-id-testimonial\" id=\"6a97c6bc7d394\"><\/div>\n        <div class=\"sd-testimonial-slider marginbottom-0px marginbottom-0px\">\n            <navigation class=\"nav-buttons-6a97c6bc7d394 nav-buttons\">\n                <div class=\"button button-prev\"><svg width=\"15\" height=\"15\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 384 512\"><path fill=\"currentColor\" d=\"M41.4 233.4c-12.5 12.5-12.5 32.8 0 45.3l192 192c12.5 12.5 32.8 12.5 45.3 0s12.5-32.8 0-45.3L109.3 256 278.6 86.6c12.5-12.5 12.5-32.8 0-45.3s-32.8-12.5-45.3 0l-192 192z\"\/><\/svg><\/div>\n                <div class=\"button button-next\"><svg width=\"15\" height=\"15\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 320 512\"><path fill=\"currentColor\" d=\"M96 480c-8.188 0-16.38-3.125-22.62-9.375c-12.5-12.5-12.5-32.75 0-45.25L242.8 256L73.38 86.63c-12.5-12.5-12.5-32.75 0-45.25s32.75-12.5 45.25 0l192 192c12.5 12.5 12.5 32.75 0 45.25l-192 192C112.4 476.9 104.2 480 96 480z\"\/><\/svg><\/div>\n            <\/navigation>\n            <div class=\"slider-inner-row-6a97c6bc7d394\" data-itemsInView=\"3\">\n                        <div id=\"slide\" class=\"slide\">\n                            <div class=\"slide-content\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"review-container\">\n\t\t\t\t\t\t\t\t\t\t\t\r\n        <div class=\"sd-block-text  marginbottom-30px color-black\r\n        \">\r\n            <p>De verhuizing van Itali\u00eb naar Nederland met mijn hele gezin was een grote stap. Ik wil de consultants van U-People hartelijk bedanken voor hun vriendelijkheid, professionaliteit en persoonlijke begeleiding.<\/p>\n\r\n        <\/div>\n\t\t\t\t\t\t\t\t\t\t\t\r\n        <div class=\"sd-block-button  marginbottom-0px color-transparent_black_border size-normal align-left full-width-no\">\r\n            <a class=\"inner-button\"\r\n            href=\"https:\/\/www.upeople.nl\/nl\/testimonial\/vincenzo\/\" title=\"Lees Vincenzozijn verhaal\">Lees Vincenzozijn verhaal<\/a>\r\n        <\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n                            \t<div class=\"person-info\">\n                            \t\t\n                            \t\t<div class=\"person-name\">\n                            \t\t\t\r\n        <div class=\"sd-block-title \">\r\n            <h3 class=\"sd-block-title-htag  marginbottom-0px align-left color-white font-mini\r\n            \">Vincenzo<\/h3>\r\n        <\/div>\n                            \t\t\t<img decoding=\"async\" class=\"person-flag\" src=\"https:\/\/www.upeople.nl\/wp-content\/uploads\/2026\/06\/Italy.svg\" alt=\"\">\n                            \t\t\t\r\n        <div class=\"sd-block-text  marginbottom-0px color-white\r\n        \">\r\n            <p>Piping Manufacturing Engineer<\/p>\n\r\n        <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n                            <\/div>\n                        <\/div>\n                        <div id=\"slide\" class=\"slide\">\n                            <div class=\"slide-content\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"review-container\">\n\t\t\t\t\t\t\t\t\t\t\t\r\n        <div class=\"sd-block-text  marginbottom-30px color-black\r\n        \">\r\n            <p>Ik beveel Upeople van harte aan bij professionals die op zoek zijn naar nieuwe carri\u00e8remogelijkheden in de maritieme sector. Ze zijn professioneel, reageren snel en zijn prettig om mee samen te werken.<\/p>\n\r\n        <\/div>\n\t\t\t\t\t\t\t\t\t\t\t\r\n        <div class=\"sd-block-button  marginbottom-0px color-transparent_black_border size-normal align-left full-width-no\">\r\n            <a class=\"inner-button\"\r\n            href=\"https:\/\/www.upeople.nl\/nl\/testimonial\/filipe\/\" title=\"Lees Filipezijn verhaal\">Lees Filipezijn verhaal<\/a>\r\n        <\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n                            \t<div class=\"person-info\">\n                            \t\t\n                            \t\t<div class=\"person-name\">\n                            \t\t\t\r\n        <div class=\"sd-block-title \">\r\n            <h3 class=\"sd-block-title-htag  marginbottom-0px align-left color-white font-mini\r\n            \">Filipe<\/h3>\r\n        <\/div>\n                            \t\t\t<img decoding=\"async\" class=\"person-flag\" src=\"https:\/\/www.upeople.nl\/wp-content\/uploads\/2026\/06\/Portugal.svg\" alt=\"\">\n                            \t\t\t\r\n        <div class=\"sd-block-text  marginbottom-0px color-white\r\n        \">\r\n            <p>Data Engineer<\/p>\n\r\n        <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n                            <\/div>\n                        <\/div>\n\t\t\t\t\t\t\t\t<div id=\"slide\" class=\"slide\">\n                            \t\t<div class=\"slide-content testimonial-content-block-container\">\n                \t\t                \r\n        <div class=\"sd-block-title \">\r\n            <h3 class=\"sd-block-title-htag  marginbottom-0px align-left color-white font-mini\r\n            \">Wil je je eigen succesverhaal?<\/h3>\r\n        <\/div>\n                                        \r\n        <div class=\"sd-block-text  marginbottom-30px color-black\r\n        \">\r\n            <p>Neem contact met ons op! Stuur ons je cv en begin aan je avontuur.<\/p>\n\r\n        <\/div>\n                            \t\t    \r\n        <div class=\"sd-block-button  marginbottom-0px color-green_background size-normal full-width-no\">\r\n            <a class=\"inner-button\"\r\n            href=\"#form\" title=\"Start de open sollicitatie\">Start de open sollicitatie<\/a>\r\n        <\/div>\n                            \t\t<\/div>\n                            \t\t<div class=\"person-info\">                            \t\t    \n                                        \n                                        <div class=\"person-name\">\n                                            \r\n        <div class=\"sd-block-title \">\r\n            <h3 class=\"sd-block-title-htag  marginbottom-0px align-left color-white font-mini\r\n            \">Jij<\/h3>\r\n        <\/div>                                           \n                                            \r\n        <div class=\"sd-block-text  marginbottom-0px color-white\r\n        \">\r\n            <p>Je droombaan<\/p>\n\r\n        <\/div>\n                                        <\/div>\n                                    <\/div>    \n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\n                        <div id=\"slide\" class=\"slide\">\n                            <div class=\"slide-content\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"review-container\">\n\t\t\t\t\t\t\t\t\t\t\t\r\n        <div class=\"sd-block-text  marginbottom-30px color-black\r\n        \">\r\n            <p>Ik waardeer de open en transparante communicatie en de vlotte afhandeling van alle administratieve zaken. Hierdoor kan ik me volledig op mijn werk concentreren.<\/p>\n\r\n        <\/div>\n\t\t\t\t\t\t\t\t\t\t\t\r\n        <div class=\"sd-block-button  marginbottom-0px color-transparent_black_border size-normal align-left full-width-no\">\r\n            <a class=\"inner-button\"\r\n            href=\"https:\/\/www.upeople.nl\/nl\/testimonial\/leen\/\" title=\"Lees Leenzijn verhaal\">Lees Leenzijn verhaal<\/a>\r\n        <\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n                            \t<div class=\"person-info\">\n                            \t\t\n                            \t\t<div class=\"person-name\">\n                            \t\t\t\r\n        <div class=\"sd-block-title \">\r\n            <h3 class=\"sd-block-title-htag  marginbottom-0px align-left color-white font-mini\r\n            \">Leen<\/h3>\r\n        <\/div>\n                            \t\t\t<img decoding=\"async\" class=\"person-flag\" src=\"https:\/\/www.upeople.nl\/wp-content\/uploads\/2026\/06\/Netherlands.svg\" alt=\"\">\n                            \t\t\t\r\n        <div class=\"sd-block-text  marginbottom-0px color-white\r\n        \">\r\n            <p>ILS Engineer<\/p>\n\r\n        <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n                            <\/div>\n                        <\/div>\n                        <div id=\"slide\" class=\"slide\">\n                            <div class=\"slide-content\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"review-container\">\n\t\t\t\t\t\t\t\t\t\t\t\r\n        <div class=\"sd-block-text  marginbottom-30px color-black\r\n        \">\r\n            <p>De samenwerking met Upeople verliep vlekkeloos, zonder problemen. Van de voorbereiding op de sollicitatiegesprekken tot de verhuizing van Spanje naar Nederland, Upeople maakte alles heel gemakkelijk voor me. Ik beveel Upeople van harte aan als je ge\u00efnteresseerd bent in een baan in de maritieme sector in Nederland.<\/p>\n\r\n        <\/div>\n\t\t\t\t\t\t\t\t\t\t\t\r\n        <div class=\"sd-block-button  marginbottom-0px color-transparent_black_border size-normal align-left full-width-no\">\r\n            <a class=\"inner-button\"\r\n            href=\"https:\/\/www.upeople.nl\/nl\/testimonial\/antonio\/\" title=\"Lees Antoniozijn verhaal\">Lees Antoniozijn verhaal<\/a>\r\n        <\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n                            \t<div class=\"person-info\">\n                            \t\t\n                            \t\t<div class=\"person-name\">\n                            \t\t\t\r\n        <div class=\"sd-block-title \">\r\n            <h3 class=\"sd-block-title-htag  marginbottom-0px align-left color-white font-mini\r\n            \">Antonio<\/h3>\r\n        <\/div>\n                            \t\t\t<img decoding=\"async\" class=\"person-flag\" src=\"https:\/\/www.upeople.nl\/wp-content\/uploads\/2026\/06\/Spain.svg\" alt=\"\">\n                            \t\t\t\r\n        <div class=\"sd-block-text  marginbottom-0px color-white\r\n        \">\r\n            <p>Tooling Engineer<\/p>\n\r\n        <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n                            <\/div>\n                        <\/div>\n\t\t\t\t\t\t\t\t<div id=\"slide\" class=\"slide\">\n                            \t\t<div class=\"slide-content testimonial-content-block-container\">\n                \t\t                \r\n        <div class=\"sd-block-title \">\r\n            <h3 class=\"sd-block-title-htag  marginbottom-0px align-left color-white font-mini\r\n            \">Wil je je eigen succesverhaal?<\/h3>\r\n        <\/div>\n                                        \r\n        <div class=\"sd-block-text  marginbottom-30px color-black\r\n        \">\r\n            <p>Neem contact met ons op! Stuur ons je cv en begin aan je avontuur.<\/p>\n\r\n        <\/div>\n                            \t\t    \r\n        <div class=\"sd-block-button  marginbottom-0px color-green_background size-normal full-width-no\">\r\n            <a class=\"inner-button\"\r\n            href=\"#form\" title=\"Start de open sollicitatie\">Start de open sollicitatie<\/a>\r\n        <\/div>\n                            \t\t<\/div>\n                            \t\t<div class=\"person-info\">                            \t\t    \n                                        \n                                        <div class=\"person-name\">\n                                            \r\n        <div class=\"sd-block-title \">\r\n            <h3 class=\"sd-block-title-htag  marginbottom-0px align-left color-white font-mini\r\n            \">Jij<\/h3>\r\n        <\/div>                                           \n                                            \r\n        <div class=\"sd-block-text  marginbottom-0px color-white\r\n        \">\r\n            <p>Je droombaan<\/p>\n\r\n        <\/div>\n                                        <\/div>\n                                    <\/div>    \n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\n                        <div id=\"slide\" class=\"slide\">\n                            <div class=\"slide-content\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"review-container\">\n\t\t\t\t\t\t\t\t\t\t\t\r\n        <div class=\"sd-block-text  marginbottom-30px color-black\r\n        \">\r\n            <p>Ik ervaar een prettige, doortastende en pragmatische samenwerking met mijn consultant bij Upeople en ben tevreden over de zeer accurate en altijd vriendelijke service van de administratie.<\/p>\n\r\n        <\/div>\n\t\t\t\t\t\t\t\t\t\t\t\r\n        <div class=\"sd-block-button  marginbottom-0px color-transparent_black_border size-normal align-left full-width-no\">\r\n            <a class=\"inner-button\"\r\n            href=\"https:\/\/www.upeople.nl\/nl\/testimonial\/frank\/\" title=\"Lees Frankzijn verhaal\">Lees Frankzijn verhaal<\/a>\r\n        <\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n                            \t<div class=\"person-info\">\n                            \t\t\n                            \t\t<div class=\"person-name\">\n                            \t\t\t\r\n        <div class=\"sd-block-title \">\r\n            <h3 class=\"sd-block-title-htag  marginbottom-0px align-left color-white font-mini\r\n            \">Frank<\/h3>\r\n        <\/div>\n                            \t\t\t<img decoding=\"async\" class=\"person-flag\" src=\"https:\/\/www.upeople.nl\/wp-content\/uploads\/2026\/06\/Netherlands.svg\" alt=\"\">\n                            \t\t\t\r\n        <div class=\"sd-block-text  marginbottom-0px color-white\r\n        \">\r\n            <p>Projectleider Nieuwbouw<\/p>\n\r\n        <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n                            <\/div>\n                        <\/div>\n                        <div id=\"slide\" class=\"slide\">\n                            <div class=\"slide-content\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"review-container\">\n\t\t\t\t\t\t\t\t\t\t\t\r\n        <div class=\"sd-block-text  marginbottom-30px color-black\r\n        \">\r\n            <p>Upeople heeft me geholpen een fantastische baan te vinden in Nederland bij een toonaangevend scheepsbouwbedrijf. Dankzij hun goede ondersteuning is mijn verhuizing van Polen naar Nederland soepel verlopen. Ik heb zowel tijdens mijn sollicitatieprocedure als gedurende de hele verhuizing goede begeleiding gekregen. Ik ben zeer tevreden.<\/p>\n\r\n        <\/div>\n\t\t\t\t\t\t\t\t\t\t\t\r\n        <div class=\"sd-block-button  marginbottom-0px color-transparent_black_border size-normal align-left full-width-no\">\r\n            <a class=\"inner-button\"\r\n            href=\"https:\/\/www.upeople.nl\/nl\/testimonial\/amadeusz\/\" title=\"Lees Amadeuszzijn verhaal\">Lees Amadeuszzijn verhaal<\/a>\r\n        <\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n                            \t<div class=\"person-info\">\n                            \t\t\n                            \t\t<div class=\"person-name\">\n                            \t\t\t\r\n        <div class=\"sd-block-title \">\r\n            <h3 class=\"sd-block-title-htag  marginbottom-0px align-left color-white font-mini\r\n            \">Amadeusz<\/h3>\r\n        <\/div>\n                            \t\t\t<img decoding=\"async\" class=\"person-flag\" src=\"https:\/\/www.upeople.nl\/wp-content\/uploads\/2026\/06\/Poland.svg\" alt=\"\">\n                            \t\t\t\r\n        <div class=\"sd-block-text  marginbottom-0px color-white\r\n        \">\r\n            <p>Engineer Configuration Management<\/p>\n\r\n        <\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n                            <\/div>\n                        <\/div>\n\t\t\t\t\t\t\t\t<div id=\"slide\" class=\"slide\">\n                            \t\t<div class=\"slide-content testimonial-content-block-container\">\n                \t\t                \r\n        <div class=\"sd-block-title \">\r\n            <h3 class=\"sd-block-title-htag  marginbottom-0px align-left color-white font-mini\r\n            \">Wil je je eigen succesverhaal?<\/h3>\r\n        <\/div>\n                                        \r\n        <div class=\"sd-block-text  marginbottom-30px color-black\r\n        \">\r\n            <p>Neem contact met ons op! Stuur ons je cv en begin aan je avontuur.<\/p>\n\r\n        <\/div>\n                            \t\t    \r\n        <div class=\"sd-block-button  marginbottom-0px color-green_background size-normal full-width-no\">\r\n            <a class=\"inner-button\"\r\n            href=\"#form\" title=\"Start de open sollicitatie\">Start de open sollicitatie<\/a>\r\n        <\/div>\n                            \t\t<\/div>\n                            \t\t<div class=\"person-info\">                            \t\t    \n                                        \n                                        <div class=\"person-name\">\n                                            \r\n        <div class=\"sd-block-title \">\r\n            <h3 class=\"sd-block-title-htag  marginbottom-0px align-left color-white font-mini\r\n            \">Jij<\/h3>\r\n        <\/div>                                           \n                                            \r\n        <div class=\"sd-block-text  marginbottom-0px color-white\r\n        \">\r\n            <p>Je droombaan<\/p>\n\r\n        <\/div>\n                                        <\/div>\n                                    <\/div>    \n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<\/div>\n        <\/div>[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; sd_bg_color=&#8221;bg_black&#8221;][vc_column]\r\n        <div class=\"sd-block-title \">\r\n            <h2 class=\"sd-block-title-htag  marginbottom-60px align-center color-white\r\n            \">Veelgestelde vragen over professionele begeleiding<\/h2>\r\n        <\/div>[vc_row_inner][vc_column_inner width=&#8221;1\/12&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;5\/12&#8243;]\r\n        <div class=\"sd-block-faq-single  marginbottom-30px color-white open-yes\">\r\n\t\t\t<div class=\"faq-inner-single\">\r\n\t\t\t\t<div class=\"faq-question\">\r\n\t\t\t\t\t<div class=\"faq-icon\">?<\/div>\r\n\t\t\t\t\t\r\n        <div class=\"sd-block-title \">\r\n            <h3 class=\"sd-block-title-htag  marginbottom-0px align-left color-white font-mini\r\n            \">Hoe begeleidt Upeople kandidaten gedurende het sollicitatieproces?<\/h3>\r\n        <\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"faq-answer\">\r\n\t\t\t\t\t\r\n        <div class=\"sd-block-text  marginbottom-0px color-white\r\n        \">\r\n            <p>Upeople biedt je persoonlijke en professionele begeleiding gedurende het hele sollicitatieproces. Tijdens het eerste gesprek bespreken we je ervaring, ambities, beschikbaarheid en voorkeuren. Vervolgens geven we je gedetailleerde informatie over de functie, de werkgever en het project, bereiden we je voor op het sollicitatiegesprek en ondersteunen we je tijdens de daaropvolgende gesprekken en contractonderhandelingen.<\/p>\n\r\n        <\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n        <\/div>\r\n        <div class=\"sd-block-faq-single  marginbottom-30px color-white open-no\">\r\n\t\t\t<div class=\"faq-inner-single\">\r\n\t\t\t\t<div class=\"faq-question\">\r\n\t\t\t\t\t<div class=\"faq-icon\">?<\/div>\r\n\t\t\t\t\t\r\n        <div class=\"sd-block-title \">\r\n            <h3 class=\"sd-block-title-htag  marginbottom-0px align-left color-white font-mini\r\n            \">Helpt Upeople me bij de voorbereiding op een sollicitatiegesprek?<\/h3>\r\n        <\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"faq-answer\">\r\n\t\t\t\t\t\r\n        <div class=\"sd-block-text  marginbottom-0px color-white\r\n        \">\r\n            <p>Ja. Voorafgaand aan het sollicitatiegesprek ontvang je relevante informatie over de organisatie, de functie, de technische werkomgeving en de interviewers. We bespreken de onderwerpen die waarschijnlijk aan bod komen en geven je advies over hoe je jouw kennis, ervaring en motivatie effectief kunt presenteren.<\/p>\n\r\n        <\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n        <\/div>\r\n        <div class=\"sd-block-faq-single  marginbottom-30px color-white open-no\">\r\n\t\t\t<div class=\"faq-inner-single\">\r\n\t\t\t\t<div class=\"faq-question\">\r\n\t\t\t\t\t<div class=\"faq-icon\">?<\/div>\r\n\t\t\t\t\t\r\n        <div class=\"sd-block-title \">\r\n            <h3 class=\"sd-block-title-htag  marginbottom-0px align-left color-white font-mini\r\n            \">Geeft Upeople advies over mijn cv?<\/h3>\r\n        <\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"faq-answer\">\r\n\t\t\t\t\t\r\n        <div class=\"sd-block-text  marginbottom-0px color-white\r\n        \">\r\n            <p>Ja. We bekijken je cv en geven gericht advies over de inhoud, structuur en relevantie ervan voor de functie. Waar nodig helpen we je jouw technische expertise, projecten, verantwoordelijkheden en prestaties duidelijker te presenteren, zodat de werkgever een volledig en accuraat beeld krijgt van jouw ervaring.<\/p>\n\r\n        <\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n        <\/div>\r\n        <div class=\"sd-block-faq-single  marginbottom-0px color-white open-no mobile_marginbottom-30px\">\r\n\t\t\t<div class=\"faq-inner-single\">\r\n\t\t\t\t<div class=\"faq-question\">\r\n\t\t\t\t\t<div class=\"faq-icon\">?<\/div>\r\n\t\t\t\t\t\r\n        <div class=\"sd-block-title \">\r\n            <h3 class=\"sd-block-title-htag  marginbottom-0px align-left color-white font-mini\r\n            \">Welke kandidaten ondersteunt Upeople?<\/h3>\r\n        <\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"faq-answer\">\r\n\t\t\t\t\t\r\n        <div class=\"sd-block-text  marginbottom-0px color-white\r\n        \">\r\n            <p>Upeople ondersteunt afgestudeerden, ervaren specialisten, senior professionals, projectmanagers, consultants en managers in de gehele maritieme technische sector. Dit omvat onder andere scheepsarchitecten, scheepsingenieurs, werktuigbouwkundigen, elektrotechnici, systeemingenieurs, interieuringenieurs, projectingenieurs, technische supervisors, service engineers, inbedrijfstellers en ILS Engineers.<\/p>\n\r\n        <\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n        <\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/12&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;5\/12&#8243;]\r\n        <div class=\"sd-block-faq-single  marginbottom-30px color-white open-no\">\r\n\t\t\t<div class=\"faq-inner-single\">\r\n\t\t\t\t<div class=\"faq-question\">\r\n\t\t\t\t\t<div class=\"faq-icon\">?<\/div>\r\n\t\t\t\t\t\r\n        <div class=\"sd-block-title \">\r\n            <h3 class=\"sd-block-title-htag  marginbottom-0px align-left color-white font-mini\r\n            \">Biedt Upeople ondersteuning bij salaris- en contractonderhandelingen?<\/h3>\r\n        <\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"faq-answer\">\r\n\t\t\t\t\t\r\n        <div class=\"sd-block-text  marginbottom-0px color-white\r\n        \">\r\n            <p>Ja. We bespreken vooraf je salarisverwachtingen, uurloon, beschikbaarheid en andere voorwaarden. Tijdens de onderhandelingen behartigen we je belangen en werken we toe naar een overeenkomst die aansluit bij je ervaring, de functie en de mogelijkheden van de werkgever.<\/p>\n\r\n        <\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n        <\/div>\r\n        <div class=\"sd-block-faq-single  marginbottom-30px color-white open-no\">\r\n\t\t\t<div class=\"faq-inner-single\">\r\n\t\t\t\t<div class=\"faq-question\">\r\n\t\t\t\t\t<div class=\"faq-icon\">?<\/div>\r\n\t\t\t\t\t\r\n        <div class=\"sd-block-title \">\r\n            <h3 class=\"sd-block-title-htag  marginbottom-0px align-left color-white font-mini\r\n            \">Blijft Upeople betrokken nadat ik met mijn nieuwe functie ben begonnen?<\/h3>\r\n        <\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"faq-answer\">\r\n\t\t\t\t\t\r\n        <div class=\"sd-block-text  marginbottom-0px color-white\r\n        \">\r\n            <p>Ja. Onze begeleiding eindigt niet na ondertekening van je arbeidsovereenkomst. We blijven gedurende de eerste werkperiode in contact en bespreken regelmatig de voortgang van de functie en de samenwerking. In het geval van detachering blijven we zowel jou als de klant gedurende de gehele opdracht begeleiden.<\/p>\n\r\n        <\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n        <\/div>\r\n        <div class=\"sd-block-faq-single  marginbottom-30px color-white open-no\">\r\n\t\t\t<div class=\"faq-inner-single\">\r\n\t\t\t\t<div class=\"faq-question\">\r\n\t\t\t\t\t<div class=\"faq-icon\">?<\/div>\r\n\t\t\t\t\t\r\n        <div class=\"sd-block-title \">\r\n            <h3 class=\"sd-block-title-htag  marginbottom-0px align-left color-white font-mini\r\n            \">Kan ik contact opnemen met Upeople als ik niet actief op zoek ben naar een nieuwe baan?<\/h3>\r\n        <\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"faq-answer\">\r\n\t\t\t\t\t\r\n        <div class=\"sd-block-text  marginbottom-0px color-white\r\n        \">\r\n            <p>Ja. Je kunt gerust vertrouwelijk contact met ons opnemen, ook als je alleen de maritieme arbeidsmarkt aan het verkennen bent. We kunnen mogelijke toekomstige carri\u00e8restappen, relevante organisaties, marktontwikkelingen en functies bespreken die aansluiten bij je ervaring en ambities.<\/p>\n\r\n        <\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n        <\/div>\r\n        <div class=\"sd-block-faq-single  marginbottom-0px color-white open-no\">\r\n\t\t\t<div class=\"faq-inner-single\">\r\n\t\t\t\t<div class=\"faq-question\">\r\n\t\t\t\t\t<div class=\"faq-icon\">?<\/div>\r\n\t\t\t\t\t\r\n        <div class=\"sd-block-title \">\r\n            <h3 class=\"sd-block-title-htag  marginbottom-0px align-left color-white font-mini\r\n            \">Hoe gaat Upeople met mijn persoonlijke gegevens om?<\/h3>\r\n        <\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"faq-answer\">\r\n\t\t\t\t\t\r\n        <div class=\"sd-block-text  marginbottom-0px color-white\r\n        \">\r\n            <p>Wij behandelen je persoonsgegevens, cv en carri\u00e8revoorkeuren zorgvuldig en vertrouwelijk. Je cv wordt nooit zonder voorafgaand overleg en zonder je toestemming met een werkgever gedeeld.<\/p>\n\r\n        <\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n        <\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; sd_row_height=&#8221;row_500px&#8221; sd_row_bottom_shape=&#8221;row_bottom_shape_3&#8243; sd_shape_color=&#8221;shape_color_white&#8221; sd_black_gradient=&#8221;yes&#8221; css=&#8221;.vc_custom_1781253986590{background-image: url(https:\/\/www.upeople.nl\/wp-content\/uploads\/2026\/06\/personal-guidance-v2.jpg?id=933) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; sd_bg_color=&#8221;bg_white&#8221;][vc_column][vc_row_inner][vc_column_inner width=&#8221;1\/12&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;10\/12&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/12&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; sd_bg_color=&#8221;bg_gray&#8221; sd_reverse_columns=&#8221;yes&#8221;][vc_column css_animation=&#8221;fadeInLeft&#8221; width=&#8221;5\/12&#8243;][\/vc_column][vc_column width=&#8221;1\/12&#8243;][\/vc_column][vc_column width=&#8221;6\/12&#8243;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; sd_row_bottom_shape=&#8221;row_bottom_shape_2&#8243; sd_shape_color=&#8221;shape_color_black&#8221; el_class=&#8221;team-overview-row&#8221; el_id=&#8221;form&#8221;][vc_column width=&#8221;2\/12&#8243;][\/vc_column][vc_column width=&#8221;1\/3&#8243; offset=&#8221;vc_col-lg-3 vc_col-md-4 vc_col-xs-6&#8243;][\/vc_column][vc_column width=&#8221;1\/12&#8243; offset=&#8221;vc_hidden-xs&#8221;][\/vc_column][vc_column css_animation=&#8221;fadeInRight&#8221; width=&#8221;5\/12&#8243; offset=&#8221;vc_col-xs-6&#8243;][\/vc_column][vc_column width=&#8221;1\/12&#8243;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; sd_bg_color=&#8221;bg_black&#8221;][vc_column][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; sd_bg_color=&#8221;bg_black&#8221;][vc_column][vc_row_inner][vc_column_inner width=&#8221;1\/12&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;5\/12&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/12&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;5\/12&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1855,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-1870","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Professionele begeleiding | U-people<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.upeople.nl\/nl\/voor-kandidaten\/professionele-begeleiding\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Professionele begeleiding | U-people\" \/>\n<meta property=\"og:description\" content=\"[vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; sd_row_height=&#8221;row_500px&#8221; sd_row_bottom_shape=&#8221;row_bottom_shape_3&#8243; sd_shape_color=&#8221;shape_color_white&#8221; sd_black_gradient=&#8221;yes&#8221; css=&#8221;.vc_custom_1781253986590{background-image: url(https:\/\/www.upeople.nl\/wp-content\/uploads\/2026\/06\/personal-guidance-v2.jpg?id=933) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; sd_bg_color=&#8221;bg_white&#8221;][vc_column][vc_row_inner][vc_column_inner width=&#8221;1\/12&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;10\/12&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/12&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; sd_bg_color=&#8221;bg_gray&#8221; sd_reverse_columns=&#8221;yes&#8221;][vc_column css_animation=&#8221;fadeInLeft&#8221; width=&#8221;5\/12&#8243;][\/vc_column][vc_column width=&#8221;1\/12&#8243;][\/vc_column][vc_column width=&#8221;6\/12&#8243;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; sd_row_bottom_shape=&#8221;row_bottom_shape_2&#8243; sd_shape_color=&#8221;shape_color_black&#8221; el_class=&#8221;team-overview-row&#8221; el_id=&#8221;form&#8221;][vc_column width=&#8221;2\/12&#8243;][\/vc_column][vc_column width=&#8221;1\/3&#8243; offset=&#8221;vc_col-lg-3 vc_col-md-4 vc_col-xs-6&#8243;][\/vc_column][vc_column width=&#8221;1\/12&#8243; offset=&#8221;vc_hidden-xs&#8221;][\/vc_column][vc_column css_animation=&#8221;fadeInRight&#8221; width=&#8221;5\/12&#8243; offset=&#8221;vc_col-xs-6&#8243;][\/vc_column][vc_column width=&#8221;1\/12&#8243;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; sd_bg_color=&#8221;bg_black&#8221;][vc_column][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; sd_bg_color=&#8221;bg_black&#8221;][vc_column][vc_row_inner][vc_column_inner width=&#8221;1\/12&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;5\/12&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/12&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;5\/12&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.upeople.nl\/nl\/voor-kandidaten\/professionele-begeleiding\/\" \/>\n<meta property=\"og:site_name\" content=\"U-people\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-21T11:07:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.upeople.nl\/wp-content\/uploads\/2026\/09\/YoastSeo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.upeople.nl\\\/nl\\\/voor-kandidaten\\\/professionele-begeleiding\\\/\",\"url\":\"https:\\\/\\\/www.upeople.nl\\\/nl\\\/voor-kandidaten\\\/professionele-begeleiding\\\/\",\"name\":\"Professionele begeleiding | U-people\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.upeople.nl\\\/nl\\\/#website\"},\"datePublished\":\"2026-04-21T08:18:06+00:00\",\"dateModified\":\"2026-08-21T11:07:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.upeople.nl\\\/nl\\\/voor-kandidaten\\\/professionele-begeleiding\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.upeople.nl\\\/nl\\\/voor-kandidaten\\\/professionele-begeleiding\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.upeople.nl\\\/nl\\\/voor-kandidaten\\\/professionele-begeleiding\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.upeople.nl\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Voor kandidaten\",\"item\":\"https:\\\/\\\/www.upeople.nl\\\/nl\\\/voor-kandidaten\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Professionele begeleiding\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.upeople.nl\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.upeople.nl\\\/nl\\\/\",\"name\":\"U-people\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.upeople.nl\\\/nl\\\/#organization\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.upeople.nl\\\/nl\\\/#organization\",\"name\":\"U-people\",\"url\":\"https:\\\/\\\/www.upeople.nl\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.upeople.nl\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.upeople.nl\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/YoastSeoLogo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.upeople.nl\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/YoastSeoLogo.jpg\",\"width\":696,\"height\":696,\"caption\":\"U-people\"},\"image\":{\"@id\":\"https:\\\/\\\/www.upeople.nl\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/u-people\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Professionele begeleiding | U-people","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.upeople.nl\/nl\/voor-kandidaten\/professionele-begeleiding\/","og_locale":"nl_NL","og_type":"article","og_title":"Professionele begeleiding | U-people","og_description":"[vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; sd_row_height=&#8221;row_500px&#8221; sd_row_bottom_shape=&#8221;row_bottom_shape_3&#8243; sd_shape_color=&#8221;shape_color_white&#8221; sd_black_gradient=&#8221;yes&#8221; css=&#8221;.vc_custom_1781253986590{background-image: url(https:\/\/www.upeople.nl\/wp-content\/uploads\/2026\/06\/personal-guidance-v2.jpg?id=933) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; sd_bg_color=&#8221;bg_white&#8221;][vc_column][vc_row_inner][vc_column_inner width=&#8221;1\/12&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;10\/12&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/12&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; sd_bg_color=&#8221;bg_gray&#8221; sd_reverse_columns=&#8221;yes&#8221;][vc_column css_animation=&#8221;fadeInLeft&#8221; width=&#8221;5\/12&#8243;][\/vc_column][vc_column width=&#8221;1\/12&#8243;][\/vc_column][vc_column width=&#8221;6\/12&#8243;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; sd_row_bottom_shape=&#8221;row_bottom_shape_2&#8243; sd_shape_color=&#8221;shape_color_black&#8221; el_class=&#8221;team-overview-row&#8221; el_id=&#8221;form&#8221;][vc_column width=&#8221;2\/12&#8243;][\/vc_column][vc_column width=&#8221;1\/3&#8243; offset=&#8221;vc_col-lg-3 vc_col-md-4 vc_col-xs-6&#8243;][\/vc_column][vc_column width=&#8221;1\/12&#8243; offset=&#8221;vc_hidden-xs&#8221;][\/vc_column][vc_column css_animation=&#8221;fadeInRight&#8221; width=&#8221;5\/12&#8243; offset=&#8221;vc_col-xs-6&#8243;][\/vc_column][vc_column width=&#8221;1\/12&#8243;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; sd_bg_color=&#8221;bg_black&#8221;][vc_column][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; sd_bg_color=&#8221;bg_black&#8221;][vc_column][vc_row_inner][vc_column_inner width=&#8221;1\/12&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;5\/12&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/12&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;5\/12&#8243;][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]","og_url":"https:\/\/www.upeople.nl\/nl\/voor-kandidaten\/professionele-begeleiding\/","og_site_name":"U-people","article_modified_time":"2026-08-21T11:07:11+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.upeople.nl\/wp-content\/uploads\/2026\/09\/YoastSeo.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.upeople.nl\/nl\/voor-kandidaten\/professionele-begeleiding\/","url":"https:\/\/www.upeople.nl\/nl\/voor-kandidaten\/professionele-begeleiding\/","name":"Professionele begeleiding | U-people","isPartOf":{"@id":"https:\/\/www.upeople.nl\/nl\/#website"},"datePublished":"2026-04-21T08:18:06+00:00","dateModified":"2026-08-21T11:07:11+00:00","breadcrumb":{"@id":"https:\/\/www.upeople.nl\/nl\/voor-kandidaten\/professionele-begeleiding\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.upeople.nl\/nl\/voor-kandidaten\/professionele-begeleiding\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.upeople.nl\/nl\/voor-kandidaten\/professionele-begeleiding\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.upeople.nl\/nl\/"},{"@type":"ListItem","position":2,"name":"Voor kandidaten","item":"https:\/\/www.upeople.nl\/nl\/voor-kandidaten\/"},{"@type":"ListItem","position":3,"name":"Professionele begeleiding"}]},{"@type":"WebSite","@id":"https:\/\/www.upeople.nl\/nl\/#website","url":"https:\/\/www.upeople.nl\/nl\/","name":"U-people","description":"","publisher":{"@id":"https:\/\/www.upeople.nl\/nl\/#organization"},"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.upeople.nl\/nl\/#organization","name":"U-people","url":"https:\/\/www.upeople.nl\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.upeople.nl\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.upeople.nl\/wp-content\/uploads\/2026\/09\/YoastSeoLogo.jpg","contentUrl":"https:\/\/www.upeople.nl\/wp-content\/uploads\/2026\/09\/YoastSeoLogo.jpg","width":696,"height":696,"caption":"U-people"},"image":{"@id":"https:\/\/www.upeople.nl\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/u-people"]}]}},"_links":{"self":[{"href":"https:\/\/www.upeople.nl\/nl\/wp-json\/wp\/v2\/pages\/1870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upeople.nl\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.upeople.nl\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.upeople.nl\/nl\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upeople.nl\/nl\/wp-json\/wp\/v2\/comments?post=1870"}],"version-history":[{"count":7,"href":"https:\/\/www.upeople.nl\/nl\/wp-json\/wp\/v2\/pages\/1870\/revisions"}],"predecessor-version":[{"id":2995,"href":"https:\/\/www.upeople.nl\/nl\/wp-json\/wp\/v2\/pages\/1870\/revisions\/2995"}],"up":[{"embeddable":true,"href":"https:\/\/www.upeople.nl\/nl\/wp-json\/wp\/v2\/pages\/1855"}],"wp:attachment":[{"href":"https:\/\/www.upeople.nl\/nl\/wp-json\/wp\/v2\/media?parent=1870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}